{"id":77,"date":"2014-09-01T00:07:48","date_gmt":"2014-08-31T23:07:48","guid":{"rendered":"https:\/\/www.md-technologie.de\/MDBlog\/?p=77"},"modified":"2014-09-01T01:08:23","modified_gmt":"2014-09-01T00:08:23","slug":"recover-raid-1-data-from-linux-lvm2-from-synology-ds414j","status":"publish","type":"post","link":"https:\/\/www.md-technologie.de\/MDBlog\/recover-raid-1-data-from-linux-lvm2-from-synology-ds414j\/","title":{"rendered":"Recover RAID 1 data from Linux LVM2 from Synology DS414j"},"content":{"rendered":"<p>Auslesen eines normalen Raid 1 (nicht SHR) von einer Synology Diskstatio DS414j<\/p>\n<p>Hierzu gibt es bereits zwei Anleitungen im Internet die mir geholfen haben:<\/p>\n<ul>\n<li>http:\/\/forum.synology.com\/enu\/viewtopic.php?f=160&amp;t=51393<\/li>\n<li>https:\/\/www.synology.com\/de-de\/knowledgebase\/faq\/579<\/li>\n<\/ul>\n<p>Wichtig war hier Ubunto zu nutzen, mit Knoppix oder Parted Magic hat es nicht funktioniert.<\/p>\n<p>Download von Ubuntu (ISO Image f\u00fcr CD oder USB): http:\/\/www.ubuntu.com\/download\/desktop<\/p>\n<p>Installieren der Raid Treiber, dazu das Terminal \u00f6ffnen (Windows-Taste und &#8222;Terminal&#8220; tippen, bei einer englischen Tastatur ist der &#8222;-&#8220; beim &#8222;\u00df&#8220;):<\/p>\n<p><strong>sudo apt-get install mdadm<\/strong><em>\u00a0<\/em> &#8211;&gt; nach der Installation mit Pfeiltaste auf OK, &#8222;No Configuration&#8220; ausw\u00e4hlen<br \/>\n<strong>sudo mdadm &#8211;assemble &#8211;scan<\/strong><\/p>\n<p>Dies hat bei mir bereits ausgereicht um im FileManager meine Partition zu finden \ud83d\ude42<\/p>\n<p>&nbsp;<\/p>\n<p>Ich habe in einem <a title=\"Recover RAID 1 data from Linux LVM2 from Promise StmartStore NS4600\" href=\"https:\/\/www.md-technologie.de\/MDBlog\/?p=47\">vorherigen Beitrag <\/a>bereits beschrieben wie ich die Daten eines Promise SmartStores NS4600 ausgelesen habe. Dieser Weg hat so bei dem Synology NAS leider nicht funktioniert. Ich bin aber froh, dass es dennoch einen Weg gibt auch die Synology Festplatten mit einem normalen PC im Notfall auszulesen.<\/p>\n<p>Weitere interessante Links:<br \/>\nhttp:\/\/forum.synology.com\/wiki\/index.php\/How_to_retrieve_data_from_RAID_Volumes_on_Linux &#8211;&gt; Beschreibung funktioniert nicht, zeigt aber gut den Aufbau einer Raid Konfiguration.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auslesen eines normalen Raid 1 (nicht SHR) von einer Synology Diskstatio DS414j Hierzu gibt es bereits zwei Anleitungen im Internet die mir geholfen haben: http:\/\/forum.synology.com\/enu\/viewtopic.php?f=160&amp;t=51393 https:\/\/www.synology.com\/de-de\/knowledgebase\/faq\/579 Wichtig war hier Ubunto zu nutzen, mit Knoppix oder Parted Magic hat es nicht funktioniert. Download von Ubuntu (ISO Image f\u00fcr CD oder USB): http:\/\/www.ubuntu.com\/download\/desktop Installieren der Raid Treiber, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[22,21,24,23],"class_list":["post-77","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-lvm2","tag-raid-1","tag-recover","tag-wiederherstellung"],"views":4556,"_links":{"self":[{"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/posts\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":7,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/posts\/77\/revisions"}],"predecessor-version":[{"id":85,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/posts\/77\/revisions\/85"}],"wp:attachment":[{"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/media?parent=77"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/categories?post=77"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.md-technologie.de\/MDBlog\/wp-json\/wp\/v2\/tags?post=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}